{"id":36951,"date":"2025-07-01T12:33:25","date_gmt":"2025-07-01T12:33:25","guid":{"rendered":"https:\/\/emit-services.com\/?p=36951"},"modified":"2026-04-01T17:05:11","modified_gmt":"2026-04-01T17:05:11","slug":"tourisme-responsable-vers-une-hospitalite-ethique-et-humaine","status":"publish","type":"post","link":"https:\/\/emit-services.com\/de\/tourisme-responsable-vers-une-hospitalite-ethique-et-humaine\/","title":{"rendered":"Verantwortungsvoller Tourismus: Auf dem Weg zu einer ethischen und menschlichen Gastfreundschaft"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"36951\" class=\"elementor elementor-36951\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-454f4d8 e-flex e-con-boxed e-con e-parent\" data-id=\"454f4d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcfe272 elementor-widget elementor-widget-heading\" data-id=\"fcfe272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eine Einladung, das Reisen zu hinterfragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88de8e6 elementor-widget elementor-widget-text-editor\" data-id=\"88de8e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Was ist Reisen anderes als das Ablegen des eigenen Wesens in einer Landschaft, die nicht die eigene ist? Die ethische Gastfreundschaft l\u00e4dt uns ein, diese Frage zu hinterfragen: Sind wir nur Besucher, oder k\u00f6nnen wir zu Akteuren eines zutiefst menschlichen Austauschs werden? In einer Zeit, in der unsere Schritte bewohnte Gebiete ber\u00fchren und unsere Augen so lebendige Kulturen streifen, erfordert ein verantwortungsvoller Tourismus ein scharfes Bewusstsein. Es reicht nicht mehr aus, nur zu bewundern: Man muss sich verbinden, das Erbe sp\u00fcren, den lokalen Erz\u00e4hlungen zuh\u00f6ren. Was w\u00e4re, wenn jede Begegnung eine offene T\u00fcr zu gegenseitigem Respekt w\u00e4re? Diese Fragestellung ist der Auftakt zu einer sinnstiftenden, edlen und bewussten Reise. Lassen Sie sich in die ethische Dimension der Gastfreundschaft f\u00fchren...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0a7618 elementor-widget elementor-widget-heading\" data-id=\"b0a7618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Globaler Kontext: Herausforderungen und Verantwortung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d344abd elementor-widget elementor-widget-text-editor\" data-id=\"d344abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Tourismus ist heute eine m\u00e4chtige Kraft: Er vermittelt Tr\u00e4ume, setzt aber auch empfindliche \u00d6kosysteme und anf\u00e4llige Gesellschaften unter Druck. Paradiesische Inseln, majest\u00e4tische Berge oder abgelegene D\u00f6rfer leiden unter einer touristischen \u00dcberlastung, die ihre Identit\u00e4t und ihr Gleichgewicht bedroht. Gleichzeitig k\u00f6nnen wirtschaftliche Gewinne die Ungleichheiten vergr\u00f6\u00dfern, wenn die lokale Bev\u00f6lkerung nicht wertgesch\u00e4tzt wird. Verantwortungsvoller Tourismus, \u00d6kotourismus oder auch gemeinschaftliche Gastfreundschaft bieten ein neues Modell: aufnehmen, ohne aufzudr\u00e4ngen, respektieren, ohne zu dominieren. Sie sind in einer nachhaltigen, ethischen und solidarischen Vision verankert. Was w\u00e4re, wenn Reisen zu einem Akt der sozialen und \u00f6kologischen Gerechtigkeit w\u00fcrde? Lesen Sie weiter, um zu erfahren, wie diese ethische Sichtweise \u00fcber den einfachen Aufenthalt hinausgeht...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36e062a elementor-widget elementor-widget-heading\" data-id=\"36e062a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Reisen als Akt der Verantwortung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e353de0 elementor-widget elementor-widget-text-editor\" data-id=\"e353de0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine verantwortungsvolle Reise anzutreten bedeutet, sich jeder Geste bewusst zu sein. Die Wahl einer solidarischen Unterkunft, die Bevorzugung sanfter Transportmittel, die Teilnahme an \u00fcberschaubaren Touren, der Beitrag zur Aufwertung des lokalen Know-hows... All dies sind Handlungen, die das Bewusstsein sch\u00e4rfen. Ethische Gastfreundschaft zeigt sich im respektvollen Dialog, im fairen Teilen, in der Aufmerksamkeit f\u00fcr Handwerker, Landwirte und Bewahrer jahrtausendealter Geschichten. Jede Geste wird zur Beleuchtung einer gemeinsamen Erz\u00e4hlung. Ein Gebiet auf diese Weise zu bereisen, bedeutet, die Menschen zu ehren, die es am Leben erhalten. Was w\u00e4re, wenn die Buchung eines Zimmers oder das Probieren eines Gerichts zu einer Art Investition in die Zukunft von Gemeinschaften w\u00fcrde? Verantwortungsvolles Reisen bereitet uns darauf vor, die vibrierende Stimme eines jeden Ortes zu h\u00f6ren...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d780a elementor-widget elementor-widget-heading\" data-id=\"83d780a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die Sch\u00f6nheit der Welt als Aufruf zu ihrer Erhaltung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5125d6 elementor-widget elementor-widget-text-editor\" data-id=\"d5125d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Angesichts eines strahlenden Sonnenuntergangs, eines dichten Prim\u00e4rwaldes, der uralten Architektur eines Steindorfes ... wird unser Staunen zu einem moralischen Vertrag. Diese Augenblicke der Sch\u00f6nheit sind die Grundlage f\u00fcr unsere Verpflichtung, das zu bewahren, was uns in Staunen versetzt. Ethische Gastfreundschaft verwandelt Kontemplation in Respekt: das Echo eines Vogelgesangs, die Frische eines Wildbachs, die W\u00e4rme einer offenen Feuerstelle. Jede Landschaft wird zu einer Leinwand, die sich aus Leben und Kultur zusammensetzt. Den Blick \u00fcber das Selfie hinaus zu richten, bedeutet, den Ruf dieser so reichen Orte zu empfangen. Was w\u00e4re, wenn das, was wir sehen, uns ver\u00e4ndern k\u00f6nnte, uns dazu bringen k\u00f6nnte, die Essenz unserer Reisen zu sch\u00fctzen? Lassen Sie sich zu dem \u00f6kologischen und menschlichen Bewusstsein der Gastfreundschaft tragen...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62533c6 elementor-widget elementor-widget-heading\" data-id=\"62533c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aufruf zum Nachdenken: Welche Werte teilen Sie?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c504cae elementor-widget elementor-widget-text-editor\" data-id=\"c504cae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reisende, Reisender: Welche Spuren m\u00f6chten Sie auf dem Weg hinterlassen? Ihre Konsumentscheidungen, Ihr Austausch, Ihr Schweigen und Ihre Worte bilden eine kollektive Erz\u00e4hlung. Jedes gekaufte Ticket, jeder Austausch in der Landessprache, jedes ehrliche L\u00e4cheln ist ein Samenkorn der Menschlichkeit. Dieses geteilte Bewusstsein baut eine Welt auf, in der der Tourismus zum Hebel der Solidarit\u00e4t und nicht zum Motor des Ungleichgewichts wird. Also: Wie m\u00f6chten Sie zu einer ethischen Gastfreundschaft beitragen? Welche Rolle wollen Sie in diesem Dialog zwischen den Kulturen spielen? Eine offene Frage und eine Einladung zu tiefem Nachdenken: Sie sind Mitautor\/in dieser Bewegung hin zu einem menschlicheren Tourismus. Lesen Sie weiter, um konkrete Gesten zu entdecken...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c6c32 elementor-widget elementor-widget-heading\" data-id=\"37c6c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anders reisen: konkrete Vorschl\u00e4ge<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c3354f elementor-widget elementor-widget-text-editor\" data-id=\"8c3354f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"4284\" data-end=\"4360\">Hier sind einige M\u00f6glichkeiten, wie Sie jeden Aufenthalt in eine verantwortungsvolle Handlung verwandeln k\u00f6nnen:<\/p><ul><li data-start=\"4363\" data-end=\"4476\"><strong data-start=\"4363\" data-end=\"4408\">W\u00e4hlen Sie lokal verwaltete Unterk\u00fcnfte<\/strong> : kleine Pensionen, Gemeinschaftsunterk\u00fcnfte, Gastgenossenschaften.<\/li><li data-start=\"4479\" data-end=\"4566\"><strong data-start=\"4479\" data-end=\"4510\">Sanfte Touren f\u00f6rdern<\/strong> : zu Fu\u00df gehen, Fahrrad fahren, umweltfreundliche \u00f6ffentliche Verkehrsmittel.<\/li><li data-start=\"4569\" data-end=\"4677\"><strong data-start=\"4569\" data-end=\"4608\">An solidarischen Projekten teilnehmen<\/strong> : Unterst\u00fctzung f\u00fcr Bildungs-, Handwerks- und Umweltinitiativen.<\/li><li data-start=\"4680\" data-end=\"4788\"><strong data-start=\"4680\" data-end=\"4708\">Traditionen respektieren<\/strong> : einige W\u00f6rter lernen, lokale Codes verstehen, sich sinnvoll kleiden.<\/li><li data-start=\"4791\" data-end=\"4890\"><strong data-start=\"4791\" data-end=\"4816\">Den Fu\u00dfabdruck verkleinern<\/strong> M\u00fcll vermeiden, kompostieren, eine Trinkflasche benutzen, Plastik vermeiden.<\/li><li><strong data-start=\"4893\" data-end=\"4918\">Handwerker unterst\u00fctzen<\/strong> : direkt einkaufen, das Handwerk respektieren, die Weitergabe begleiten.<\/li><\/ul><p>Diese scheinbar einfachen Gesten tragen eine echte Ver\u00e4nderung in sich: Sie machen den Tourismus zu einem Raum der tiefen Begegnung, des fairen Teilens und des Aufwachens f\u00fcr den Anderen. Was w\u00e4re, wenn jedem Horizont eine ethische Entscheidung entspr\u00e4che? Der n\u00e4chste Absatz enth\u00fcllt die Vision einer m\u00f6glichen Zukunft...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62dfe3b elementor-widget elementor-widget-heading\" data-id=\"62dfe3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Eine gemeinsame Zukunft: Hoffnung und Engagement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18b8f9e elementor-widget elementor-widget-text-editor\" data-id=\"18b8f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stellen Sie sich eine Welt vor, in der jeder Aufenthalt einen Faden zwischen den V\u00f6lkern webt, in der das Reisen nicht aus dem Gleichgewicht bringt, sondern n\u00e4hrt, in der Gastfreundschaft zu einem Akt der Liebe f\u00fcr die Erde und ihre V\u00f6lker wird. Eine Welt, in der sich Staunen auf Engagement, Entdecken auf Verantwortung und Begegnung auf Solidarit\u00e4t reimt. Gemeinsam k\u00f6nnen wir diese Zukunft gestalten: Reisende, die zu H\u00fctern der Gebiete werden, Gastgeber, die das Wissen aufwerten, Strukturen, die das Gemeinwohl unterst\u00fctzen. Nachhaltiger Tourismus, \u00d6kotourismus, verantwortungsbewusster Tourismus - diese Worte werden zu unseren Leuchtt\u00fcrmen. Jetzt sind Sie an der Reihe: Teilen Sie Ihre Ideen, Ihre Tr\u00e4ume von ethischen Reisen, Ihre engagierten Praktiken. Lassen Sie uns gemeinsam dieses poetische und solidarische Manifest verfassen: Die Gastfreundschaft von morgen ist unsere Gastfreundschaft, die einer respektierten und verbundenen Welt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea51c5c e-flex e-con-boxed e-con e-parent\" data-id=\"ea51c5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-69af566 e-con-full e-flex e-con e-child\" data-id=\"69af566\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02b0c52 elementor-widget elementor-widget-image\" data-id=\"02b0c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/emit-services.com\/wp-content\/uploads\/2025\/07\/Tourisme-responsable-_-Vers-une-hospitalite-ethique-et-humaine-2-800x450.jpg\" class=\"attachment-ocean-thumb-ml size-ocean-thumb-ml wp-image-43129\" alt=\"Plage dor\u00e9e bord\u00e9e de rochers noirs sous un ciel nuageux, avec des vagues douces et des palmiers \u00e0 l\u2019horizon.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba9f456 e-con-full e-flex e-con e-child\" data-id=\"ba9f456\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b63dfc elementor-widget elementor-widget-image\" data-id=\"2b63dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/emit-services.com\/wp-content\/uploads\/2025\/07\/Tourisme-responsable-_-Vers-une-hospitalite-ethique-et-humaine-800x450.jpg\" class=\"attachment-ocean-thumb-ml size-ocean-thumb-ml wp-image-43130\" alt=\"Canard femelle canard colvert nageant avec ses canetons sur l\u2019eau\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca2aa9b e-flex e-con-boxed e-con e-parent\" data-id=\"ca2aa9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-046272f elementor-widget elementor-widget-heading\" data-id=\"046272f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Auch lesenswert<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c076f elementor-widget elementor-widget-text-editor\" data-id=\"44c076f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/emit-services.com\/de\/voyager-en-conscience-voir-comprendre-respecter\/\">Bewusst reisen: Sehen, verstehen, respektieren<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f38784 elementor-widget elementor-widget-text-editor\" data-id=\"3f38784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/emit-services.com\/de\/voyages-a-impact-inspirer-sans-exploiter\/\">Voyages \u00e0 impact : Inspirer sans exploiter<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f6bc70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f6bc70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-140448d\" data-id=\"140448d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f04c7db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f04c7db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e5571f\" data-id=\"1e5571f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7c1967 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"d7c1967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilen :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cc15f40\" data-id=\"cc15f40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f79a30 elementor-share-buttons--skin-flat elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-share-buttons--view-icon-text elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"9f79a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_pinterest\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur pinterest\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pinterest\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 256c0 137-111 248-248 248-25.6 0-50.2-3.9-73.4-11.1 10.1-16.5 25.2-43.5 30.8-65 3-11.6 15.4-59 15.4-59 8.1 15.4 31.7 28.5 56.8 28.5 74.8 0 128.7-68.8 128.7-154.3 0-81.9-66.9-143.2-152.9-143.2-107 0-163.9 71.8-163.9 150.1 0 36.4 19.4 81.7 50.3 96.1 4.7 2.2 7.2 1.2 8.3-3.3.8-3.4 5-20.3 6.9-28.1.6-2.5.3-4.7-1.7-7.1-10.1-12.5-18.3-35.3-18.3-56.6 0-54.7 41.4-107.6 112-107.6 60.9 0 103.6 41.5 103.6 100.9 0 67.1-33.9 113.6-78 113.6-24.3 0-42.6-20.1-36.7-44.8 7-29.5 20.5-61.3 20.5-82.6 0-19-10.2-34.9-31.4-34.9-24.9 0-44.9 25.7-44.9 60.2 0 22 7.4 36.8 7.4 36.8s-24.5 103.8-29 123.2c-5 21.4-3 51.6-.9 71.2C65.4 450.9 0 361.1 0 256 0 119 111 8 248 8s248 111 248 248z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tPinterest\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur whatsapp\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Une invitation \u00e0 questionner le voyage Qu\u2019est-ce que voyager, si ce n\u2019est d\u00e9poser son \u00eatre dans un paysage qui n\u2019est pas le sien ? L\u2019hospitalit\u00e9 \u00e9thique nous invite \u00e0 interroger cette question : sommes-nous simplement visiteurs, ou pouvons\u2011nous devenir des actrices et des acteurs d\u2019un \u00e9change profond\u00e9ment humain\u202f? \u00c0 l\u2019heure o\u00f9 nos pas effleurent des [&hellip;]<\/p>","protected":false},"author":204,"featured_media":36953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[350],"tags":[],"class_list":["post-36951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tourisme-responsable","entry","has-media","owp-thumbs-layout-vertical","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/posts\/36951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/users\/204"}],"replies":[{"embeddable":true,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/comments?post=36951"}],"version-history":[{"count":10,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/posts\/36951\/revisions"}],"predecessor-version":[{"id":48253,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/posts\/36951\/revisions\/48253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/media\/36953"}],"wp:attachment":[{"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/media?parent=36951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/categories?post=36951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emit-services.com\/de\/wp-json\/wp\/v2\/tags?post=36951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}